{"id":11202,"date":"2023-12-18T11:54:32","date_gmt":"2023-12-18T16:54:32","guid":{"rendered":"https:\/\/magicdichol.info\/cumparati-acum\/"},"modified":"2025-04-15T04:41:31","modified_gmt":"2025-04-15T09:41:31","slug":"cumparati-acum","status":"publish","type":"page","link":"https:\/\/magicdichol.info\/ro\/cumparati-acum\/","title":{"rendered":"Cump\u0103ra\u021bi acum"},"content":{"rendered":"\n\t<div id=\"gap-1587138203\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1587138203 {\n  padding-top: 80px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section\" id=\"section_1178309873\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\n<div class=\"row row-small\"  id=\"row-180546599\">\n\n\n\t<div id=\"col-495474610\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2808581185\" class=\"text\">\n\t\t\n\n\n\t\t\n<style>\n#text-2808581185 {\n  color: rgb(0,0,0);\n}\n#text-2808581185 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-20304225\" class=\"text\">\n\t\t\n\n<p><strong>Dac\u0103 v\u0103 afla\u021bi \u00een SUA \u0219i Canada, utiliza\u021bi co\u0219ul de cump\u0103r\u0103turi de mai jos; dar dac\u0103 v\u0103 afla\u021bi \u00een alte \u021b\u0103ri, utiliza\u021bi aceste butoane:<\/strong><\/p>\n\t\t\n<style>\n#text-20304225 {\n  line-height: 1.3;\n  text-align: center;\n  color: rgb(0,0,0);\n}\n#text-20304225 > * {\n  color: rgb(0,0,0);\n}\n@media (min-width:550px) {\n  #text-20304225 {\n    line-height: 0.75;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row row-collapse\"  id=\"row-1290320905\">\n\n\n\t<div id=\"col-362129012\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/www.magicdichol.com\/store\/mdaust\/\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\">\n\t\t<span>AUSTRALIA<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-362129012 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-506499127\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/www.magicdichol.com\/store\/mdeurope\/\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\">\n\t\t<span>UNIUNEA EUROPEAN\u0102<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1379468835\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/www.magicdichol.com\/store\/mduk\/\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\">\n\t\t<span>REGATUL UNIT<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-1290320905 > .col > .col-inner {\n  padding: 0px 10px 0px 10px;\n}\n<\/style>\n<\/div>\n<div class=\"row row-collapse\"  id=\"row-2004665802\">\n\n\n\t<div id=\"col-1922901894\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/www.magicdichol.com\/store\/mdnz\/\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\">\n\t\t<span>NOUA ZEELAND\u0102<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1922901894 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-810451993\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"https:\/\/www.magicdichol.com\/store\/mdhk\/\" target=\"_blank\" class=\"button primary expand\" rel=\"noopener\">\n\t\t<span>HONG KONG<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-2004665802 > .col > .col-inner {\n  padding: 0px 10px 0px 10px;\n}\n<\/style>\n<\/div>\n\t<div id=\"gap-41401286\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-41401286 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-4146264669\" class=\"text\">\n\t\t\n\n<h2>Produse<\/h2>\n<p>Experimenta\u021bi beneficiile complete ale familiei de produse MagicDichol.<\/p>\n\t\t\n<style>\n#text-4146264669 {\n  line-height: 1.3;\n  color: rgb(0,0,0);\n}\n#text-4146264669 > * {\n  color: rgb(0,0,0);\n}\n@media (min-width:550px) {\n  #text-4146264669 {\n    line-height: 0.75;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1130417838\">\n\n\n\t<div id=\"col-1503000701\" class=\"col hide-for-small medium-2 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2092189892\" class=\"col medium-8 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\n  \n    <div class=\"row large-columns-1 medium-columns- small-columns- row-small\" >\n  \n\t     <div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/magicdichol.info\/ro\/produs\/magicdichol-pachet-de-pornire\/\" aria-label=\"MagicDichol\u00ae Pachet de pornire\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"400\" src=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/MD-Starter-Pack-New-Cream-High-Quality-1.jpg\" class=\"attachment-original size-original\" alt=\"MagicDichol\u00ae Pachet de pornire\" srcset=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/MD-Starter-Pack-New-Cream-High-Quality-1.jpg 580w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/MD-Starter-Pack-New-Cream-High-Quality-1-300x207.jpg 300w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/MD-Starter-Pack-New-Cream-High-Quality-1-510x352.jpg 510w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"13994\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Previzualizare rapid\u0103<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" >\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tPachet de pornire\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/magicdichol.info\/ro\/produs\/magicdichol-pachet-de-pornire\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">MagicDichol\u00ae Pachet de pornire<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>395.00<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Pre\u021bul ini\u021bial a fost: &#036;395.00.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>335.75<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Pre\u021bul curent este: &#036;335.75.<\/span><\/span>\n<\/div><div class=\"add-to-cart-button\"><a href=\"\/ro\/wp-json\/wp\/v2\/pages\/11202?add-to-cart=13994\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_13994\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_simple add_to_cart_button ajax_add_to_cart is-outline\" data-product_id=\"13994\" data-product_sku=\"START01\" aria-label=\"Adaug\u0103 \u00een co\u0219: &amp;lbquo;MagicDichol\u00ae Pachet de pornire&rdquo;\" rel=\"nofollow\" data-success_message=\"&bdquo;MagicDichol\u00ae Pachet de pornire&rdquo; a fost ad\u0103ugat \u00een co\u0219\" role=\"button\">Adaug\u0103 \u00een co\u0219<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_13994\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-834287166\" class=\"col hide-for-small medium-2 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1178309873 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t\n  \n    <div class=\"row  equalize-box large-columns-3 medium-columns- small-columns-2 row-small\" >\n  \n\t     <div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/magicdichol.info\/ro\/produs\/nano-soma-lichid\/\" aria-label=\"NANO SOMA\u00ae Liquid\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1142\" height=\"1286\" src=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/USNS1BottleGradient20Nov2023.png\" class=\"attachment-original size-original\" alt=\"NANO SOMA\u00ae Liquid\" srcset=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/USNS1BottleGradient20Nov2023.png 1142w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/USNS1BottleGradient20Nov2023-510x574.png 510w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/USNS1BottleGradient20Nov2023-266x300.png 266w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/USNS1BottleGradient20Nov2023-909x1024.png 909w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/USNS1BottleGradient20Nov2023-768x865.png 768w\" sizes=\"auto, (max-width: 1142px) 100vw, 1142px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"14091\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Previzualizare rapid\u0103<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:10px 10px 20px 10px;\">\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tS\u0103n\u0103tate\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/magicdichol.info\/ro\/produs\/nano-soma-lichid\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">NANO SOMA\u00ae Liquid<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>57.00<\/bdi><\/span><\/span>\n<\/div><div class=\"add-to-cart-button\"><a href=\"\/ro\/wp-json\/wp\/v2\/pages\/11202?add-to-cart=14091\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14091\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_simple add_to_cart_button ajax_add_to_cart is-outline\" data-product_id=\"14091\" data-product_sku=\"\" aria-label=\"Adaug\u0103 \u00een co\u0219: &amp;lbquo;NANO SOMA\u00ae Liquid&rdquo;\" rel=\"nofollow\" data-success_message=\"&bdquo;NANO SOMA\u00ae Liquid&rdquo; a fost ad\u0103ugat \u00een co\u0219\" role=\"button\">Adaug\u0103 \u00een co\u0219<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14091\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/magicdichol.info\/ro\/produs\/nano-soma-gel-topic\/\" aria-label=\"NANO SOMA\u00ae Topical Gel\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1142\" height=\"1286\" src=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_002.jpeg\" class=\"attachment-original size-original\" alt=\"NANO SOMA\u00ae Topical Gel\" srcset=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_002.jpeg 1142w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_002-266x300.jpeg 266w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_002-909x1024.jpeg 909w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_002-768x865.jpeg 768w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_002-510x574.jpeg 510w\" sizes=\"auto, (max-width: 1142px) 100vw, 1142px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"14067\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Previzualizare rapid\u0103<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:10px 10px 20px 10px;\">\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tS\u0103n\u0103tate\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/magicdichol.info\/ro\/produs\/nano-soma-gel-topic\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">NANO SOMA\u00ae Topical Gel<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>87.00<\/bdi><\/span><\/span>\n<\/div><div class=\"add-to-cart-button\"><a href=\"\/ro\/wp-json\/wp\/v2\/pages\/11202?add-to-cart=14067\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14067\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_simple add_to_cart_button ajax_add_to_cart is-outline\" data-product_id=\"14067\" data-product_sku=\"GEL01\" aria-label=\"Adaug\u0103 \u00een co\u0219: &amp;lbquo;NANO SOMA\u00ae Topical Gel&rdquo;\" rel=\"nofollow\" data-success_message=\"&bdquo;NANO SOMA\u00ae Topical Gel&rdquo; a fost ad\u0103ugat \u00een co\u0219\" role=\"button\">Adaug\u0103 \u00een co\u0219<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14067\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/magicdichol.info\/ro\/produs\/crema-de-piele-nano-soma\/\" aria-label=\"NANO SOMA\u00ae Skin Cream\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1142\" height=\"1286\" src=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/signal-2025-10-18-203311_002.jpg\" class=\"attachment-original size-original\" alt=\"NANO SOMA\u00ae Skin Cream\" srcset=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/signal-2025-10-18-203311_002.jpg 1142w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/signal-2025-10-18-203311_002-266x300.jpg 266w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/signal-2025-10-18-203311_002-909x1024.jpg 909w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/signal-2025-10-18-203311_002-768x865.jpg 768w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/signal-2025-10-18-203311_002-510x574.jpg 510w\" sizes=\"auto, (max-width: 1142px) 100vw, 1142px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"14054\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Previzualizare rapid\u0103<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:10px 10px 20px 10px;\">\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\tS\u0103n\u0103tate\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/magicdichol.info\/ro\/produs\/crema-de-piele-nano-soma\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">NANO SOMA\u00ae Skin Cream<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>137.00<\/bdi><\/span><\/span>\n<\/div><div class=\"add-to-cart-button\"><a href=\"\/ro\/wp-json\/wp\/v2\/pages\/11202?add-to-cart=14054\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14054\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_simple add_to_cart_button ajax_add_to_cart is-outline\" data-product_id=\"14054\" data-product_sku=\"\" aria-label=\"Adaug\u0103 \u00een co\u0219: &amp;lbquo;NANO SOMA\u00ae Skin Cream&rdquo;\" rel=\"nofollow\" data-success_message=\"&bdquo;NANO SOMA\u00ae Skin Cream&rdquo; a fost ad\u0103ugat \u00een co\u0219\" role=\"button\">Adaug\u0103 \u00een co\u0219<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14054\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/magicdichol.info\/ro\/produs\/nano-soma-lichid-pachet-de-3\/\" aria-label=\"NANO SOMA\u00ae Liquid - pachet de 3\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1142\" height=\"1286\" src=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/USNS3PACKBottlesGradient20Nov2023.png\" class=\"attachment-original size-original\" alt=\"NANO SOMA\u00ae Liquid - pachet de 3\" srcset=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/USNS3PACKBottlesGradient20Nov2023.png 1142w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/USNS3PACKBottlesGradient20Nov2023-510x574.png 510w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/USNS3PACKBottlesGradient20Nov2023-266x300.png 266w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/USNS3PACKBottlesGradient20Nov2023-909x1024.png 909w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/USNS3PACKBottlesGradient20Nov2023-768x865.png 768w\" sizes=\"auto, (max-width: 1142px) 100vw, 1142px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"14050\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Previzualizare rapid\u0103<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:10px 10px 20px 10px;\">\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\t3 pachete\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/magicdichol.info\/ro\/produs\/nano-soma-lichid-pachet-de-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">NANO SOMA\u00ae Liquid &#8211; pachet de 3<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>171.00<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Pre\u021bul ini\u021bial a fost: &#036;171.00.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>153.90<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Pre\u021bul curent este: &#036;153.90.<\/span><\/span>\n<\/div><div class=\"add-to-cart-button\"><a href=\"\/ro\/wp-json\/wp\/v2\/pages\/11202?add-to-cart=14050\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14050\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_simple add_to_cart_button ajax_add_to_cart is-outline\" data-product_id=\"14050\" data-product_sku=\"\" aria-label=\"Adaug\u0103 \u00een co\u0219: &amp;lbquo;NANO SOMA\u00ae Liquid - pachet de 3&rdquo;\" rel=\"nofollow\" data-success_message=\"&bdquo;NANO SOMA\u00ae Liquid - pachet de 3&rdquo; a fost ad\u0103ugat \u00een co\u0219\" role=\"button\">Adaug\u0103 \u00een co\u0219<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14050\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/magicdichol.info\/ro\/produs\/nano-soma-gel-topic-pachet-de-3\/\" aria-label=\"NANO SOMA\u00ae Topical Gel - pachet de 3\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1142\" height=\"1286\" src=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_003.jpeg\" class=\"attachment-original size-original\" alt=\"NANO SOMA\u00ae Topical Gel - pachet de 3\" srcset=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_003.jpeg 1142w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_003-266x300.jpeg 266w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_003-909x1024.jpeg 909w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_003-768x865.jpeg 768w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_003-510x574.jpeg 510w\" sizes=\"auto, (max-width: 1142px) 100vw, 1142px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"14101\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Previzualizare rapid\u0103<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:10px 10px 20px 10px;\">\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\t3 pachete\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/magicdichol.info\/ro\/produs\/nano-soma-gel-topic-pachet-de-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">NANO SOMA\u00ae Topical Gel &#8211; pachet de 3<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>261.00<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Pre\u021bul ini\u021bial a fost: &#036;261.00.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>234.90<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Pre\u021bul curent este: &#036;234.90.<\/span><\/span>\n<\/div><div class=\"add-to-cart-button\"><a href=\"\/ro\/wp-json\/wp\/v2\/pages\/11202?add-to-cart=14101\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14101\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_simple add_to_cart_button ajax_add_to_cart is-outline\" data-product_id=\"14101\" data-product_sku=\"GEL03\" aria-label=\"Adaug\u0103 \u00een co\u0219: &amp;lbquo;NANO SOMA\u00ae Topical Gel - pachet de 3&rdquo;\" rel=\"nofollow\" data-success_message=\"&bdquo;NANO SOMA\u00ae Topical Gel - pachet de 3&rdquo; a fost ad\u0103ugat \u00een co\u0219\" role=\"button\">Adaug\u0103 \u00een co\u0219<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14101\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/magicdichol.info\/ro\/produs\/crema-de-piele-nano-soma-3-pack\/\" aria-label=\"NANO SOMA\u00ae Skin Cream 3-pack\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1142\" height=\"1286\" src=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/signal-2025-10-18-203311_003.jpeg\" class=\"attachment-original size-original\" alt=\"NANO SOMA\u00ae Skin Cream 3-pack\" srcset=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/signal-2025-10-18-203311_003.jpeg 1142w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/signal-2025-10-18-203311_003-266x300.jpeg 266w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/signal-2025-10-18-203311_003-909x1024.jpeg 909w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/signal-2025-10-18-203311_003-768x865.jpeg 768w, https:\/\/magicdichol.info\/wp-content\/uploads\/2023\/12\/signal-2025-10-18-203311_003-510x574.jpeg 510w\" sizes=\"auto, (max-width: 1142px) 100vw, 1142px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"14035\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Previzualizare rapid\u0103<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:10px 10px 20px 10px;\">\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\t3 pachete\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/magicdichol.info\/ro\/produs\/crema-de-piele-nano-soma-3-pack\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">NANO SOMA\u00ae Skin Cream 3-pack<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>411.00<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Pre\u021bul ini\u021bial a fost: &#036;411.00.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>369.90<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Pre\u021bul curent este: &#036;369.90.<\/span><\/span>\n<\/div><div class=\"add-to-cart-button\"><a href=\"\/ro\/wp-json\/wp\/v2\/pages\/11202?add-to-cart=14035\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14035\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_simple add_to_cart_button ajax_add_to_cart is-outline\" data-product_id=\"14035\" data-product_sku=\"\" aria-label=\"Adaug\u0103 \u00een co\u0219: &amp;lbquo;NANO SOMA\u00ae Skin Cream 3-pack&rdquo;\" rel=\"nofollow\" data-success_message=\"&bdquo;NANO SOMA\u00ae Skin Cream 3-pack&rdquo; a fost ad\u0103ugat \u00een co\u0219\" role=\"button\">Adaug\u0103 \u00een co\u0219<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14035\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/magicdichol.info\/ro\/produs\/nano-soma-lichid-pachet-de-12\/\" aria-label=\"NANO SOMA\u00ae Liquid - pachet de 12\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1142\" height=\"1286\" src=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/USNS12PACKBottlesGradient20Nov2023.png\" class=\"attachment-original size-original\" alt=\"NANO SOMA\u00ae Liquid - pachet de 12\" srcset=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/USNS12PACKBottlesGradient20Nov2023.png 1142w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/USNS12PACKBottlesGradient20Nov2023-510x574.png 510w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/USNS12PACKBottlesGradient20Nov2023-266x300.png 266w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/USNS12PACKBottlesGradient20Nov2023-909x1024.png 909w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/USNS12PACKBottlesGradient20Nov2023-768x865.png 768w\" sizes=\"auto, (max-width: 1142px) 100vw, 1142px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"14084\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Previzualizare rapid\u0103<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:10px 10px 20px 10px;\">\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\t12 pachete\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/magicdichol.info\/ro\/produs\/nano-soma-lichid-pachet-de-12\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">NANO SOMA\u00ae Liquid &#8211; pachet de 12<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>684.00<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Pre\u021bul ini\u021bial a fost: &#036;684.00.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>581.40<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Pre\u021bul curent este: &#036;581.40.<\/span><\/span>\n<\/div><div class=\"add-to-cart-button\"><a href=\"\/ro\/wp-json\/wp\/v2\/pages\/11202?add-to-cart=14084\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14084\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_simple add_to_cart_button ajax_add_to_cart is-outline\" data-product_id=\"14084\" data-product_sku=\"\" aria-label=\"Adaug\u0103 \u00een co\u0219: &amp;lbquo;NANO SOMA\u00ae Liquid - pachet de 12&rdquo;\" rel=\"nofollow\" data-success_message=\"&bdquo;NANO SOMA\u00ae Liquid - pachet de 12&rdquo; a fost ad\u0103ugat \u00een co\u0219\" role=\"button\">Adaug\u0103 \u00een co\u0219<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14084\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/magicdichol.info\/ro\/produs\/nano-soma-gel-topic-12\/\" aria-label=\"NANO SOMA\u00ae Topical Gel - 12\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1142\" height=\"1286\" src=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_004.jpeg\" class=\"attachment-original size-original\" alt=\"NANO SOMA\u00ae Topical Gel - 12\" srcset=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_004.jpeg 1142w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_004-266x300.jpeg 266w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_004-909x1024.jpeg 909w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_004-768x865.jpeg 768w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-03-28-144430_004-510x574.jpeg 510w\" sizes=\"auto, (max-width: 1142px) 100vw, 1142px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"14021\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Previzualizare rapid\u0103<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:10px 10px 20px 10px;\">\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\t12 pachete\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/magicdichol.info\/ro\/produs\/nano-soma-gel-topic-12\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">NANO SOMA\u00ae Topical Gel &#8211; 12<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>1,044.00<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Pre\u021bul ini\u021bial a fost: &#036;1,044.00.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>887.40<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Pre\u021bul curent este: &#036;887.40.<\/span><\/span>\n<\/div><div class=\"add-to-cart-button\"><a href=\"\/ro\/wp-json\/wp\/v2\/pages\/11202?add-to-cart=14021\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14021\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_simple add_to_cart_button ajax_add_to_cart is-outline\" data-product_id=\"14021\" data-product_sku=\"GEL12\" aria-label=\"Adaug\u0103 \u00een co\u0219: &amp;lbquo;NANO SOMA\u00ae Topical Gel - 12&rdquo;\" rel=\"nofollow\" data-success_message=\"&bdquo;NANO SOMA\u00ae Topical Gel - 12&rdquo; a fost ad\u0103ugat \u00een co\u0219\" role=\"button\">Adaug\u0103 \u00een co\u0219<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14021\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><div class=\"col\" >\n\t\t\t\t\t\t<div class=\"col-inner\">\n\t\t\t\t\t\t\n<div class=\"badge-container absolute left top z-1\">\n\n<\/div>\n\t\t\t\t\t\t<div class=\"product-small box has-hover box-normal box-text-bottom\">\n\t\t\t\t\t\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/magicdichol.info\/ro\/produs\/crema-de-piele-nano-soma-pachet-de-12\/\" aria-label=\"NANO SOMA\u00ae Skin Cream Pachet de 12\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1142\" height=\"1286\" src=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-10-18-203311_004.jpeg\" class=\"attachment-original size-original\" alt=\"NANO SOMA\u00ae Skin Cream Pachet de 12\" srcset=\"https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-10-18-203311_004.jpeg 1142w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-10-18-203311_004-266x300.jpeg 266w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-10-18-203311_004-909x1024.jpeg 909w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-10-18-203311_004-768x865.jpeg 768w, https:\/\/magicdichol.info\/wp-content\/uploads\/2024\/02\/signal-2025-10-18-203311_004-510x574.jpeg 510w\" sizes=\"auto, (max-width: 1142px) 100vw, 1142px\" \/>\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"image-tools top right show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image-tools grid-tools text-center hide-for-small bottom hover-slide-in show-on-hover\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"#quick-view\" class=\"quick-view\" role=\"button\" data-prod=\"14009\" aria-haspopup=\"dialog\" aria-expanded=\"false\" data-flatsome-role-button>Previzualizare rapid\u0103<\/a>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"box-text text-center\" style=\"padding:10px 10px 20px 10px;\">\n\t\t\t\t\t\t\t\t<div class=\"title-wrapper\">\t\t<p class=\"category uppercase is-smaller no-text-overflow product-cat op-8\">\n\t\t\t12 pachete\t\t<\/p>\n\t<p class=\"name product-title woocommerce-loop-product__title\"><a href=\"https:\/\/magicdichol.info\/ro\/produs\/crema-de-piele-nano-soma-pachet-de-12\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">NANO SOMA\u00ae Skin Cream Pachet de 12<\/a><\/p><\/div><div class=\"price-wrapper\">\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>1,644.00<\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Pre\u021bul ini\u021bial a fost: &#036;1,644.00.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&#36;<\/span>1,397.40<\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Pre\u021bul curent este: &#036;1,397.40.<\/span><\/span>\n<\/div><div class=\"add-to-cart-button\"><a href=\"\/ro\/wp-json\/wp\/v2\/pages\/11202?add-to-cart=14009\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14009\" data-quantity=\"1\" class=\"primary is-small mb-0 button product_type_simple add_to_cart_button ajax_add_to_cart is-outline\" data-product_id=\"14009\" data-product_sku=\"\" aria-label=\"Adaug\u0103 \u00een co\u0219: &amp;lbquo;NANO SOMA\u00ae Skin Cream Pachet de 12&rdquo;\" rel=\"nofollow\" data-success_message=\"&bdquo;NANO SOMA\u00ae Skin Cream Pachet de 12&rdquo; a fost ad\u0103ugat \u00een co\u0219\" role=\"button\">Adaug\u0103 \u00een co\u0219<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14009\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div><\/div>\n\n\t<div id=\"gap-1264029028\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1264029028 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t<section class=\"section\" id=\"section_10412654\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t<div id=\"gap-1418119468\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1418119468 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-1671388261\">\n\n\n\t<div id=\"col-1198028018\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3539158164\" class=\"text\">\n\t\t\n\n<h2>Pove\u0219ti reale. Transform\u0103ri reale. <\/h2>\n<p>Vede\u021bi ce spun clien\u021bii no\u0219tri despre produsele noastre<\/p>\n\t\t\n<style>\n#text-3539158164 {\n  font-size: 1.2rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-equal\"  id=\"row-1330444277\">\n\n\n\t<div id=\"col-60437902\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 1px 1px 1px;\">\n\t<\/div>\n\t\t\t\n\n  <div class=\"icon-box testimonial-box icon-box-center text-center\">\n                <div class=\"icon-box-text p-last-0\">\n            \t\t\t\t<div class=\"testimonial-text line-height-small italic test_text first-reset last-reset is-italic\">\n            \n\n\t<div id=\"gap-1324422732\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1324422732 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p style=\"font-style: normal;\">&#8222;Folosesc NANO SOMA\u00ae de aproximativ trei luni. \u00cen ultima vreme, oric\u00e2t de nebunesc ar p\u0103rea, am observat mai multe instrumente \u00een muzica pe care o ascult. Aud mici sunete de fundal pe care nu le observasem niciodat\u0103 \u00eenainte. Auzul meu a fost \u00eentotdeauna bun, dar pare mai bun. De asemenea, sinusurile mele nu au fost niciodat\u0103 mai bune.\u201d<\/p>\n\n          <\/div>\n          <div class=\"testimonial-meta pt-half\">\n             <strong class=\"testimonial-name test_name\">Bonnie<\/strong>\n                          <span class=\"testimonial-company test_company\"><\/span>\n          <\/div>\n        <\/div>\n  <\/div>\n\n  \n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-673199237\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 1px 1px 1px;\">\n\t<\/div>\n\t\t\t\n\n  <div class=\"icon-box testimonial-box icon-box-center text-center\">\n                <div class=\"icon-box-text p-last-0\">\n            \t\t\t\t<div class=\"testimonial-text line-height-small italic test_text first-reset last-reset is-italic\">\n            \n\n\t<div id=\"gap-940254801\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-940254801 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p style=\"font-style: normal;\">&#8222;Am f\u0103cut cafea cu ap\u0103 clocotit\u0103 \u0219i mi-am scaldat \u00eencheietura \u0219i bra\u021bul. A fost instantaneu ro\u0219u \u0219i foarte sensibil. Am aplicat o cantitate mic\u0103 de NANO SOMA\u00ae Topical Gel pe arsur\u0103. A usturat la contact, dar a calmat-o aproape instantaneu. Aproximativ dou\u0103zeci de minute mai t\u00e2rziu, am mai aplicat NANO SOMA\u00ae Topical Gel \u00eenainte de a merge la culcare. C\u00e2teva ore mai t\u00e2rziu, pielea mea este complet calmat\u0103.\u201d<\/p>\n\n          <\/div>\n          <div class=\"testimonial-meta pt-half\">\n             <strong class=\"testimonial-name test_name\">Barbara<\/strong>\n                          <span class=\"testimonial-company test_company\"><\/span>\n          <\/div>\n        <\/div>\n  <\/div>\n\n  \n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1954868518\" class=\"col medium-6 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:1px 1px 1px 1px;\">\n\t<\/div>\n\t\t\t\n\n  <div class=\"icon-box testimonial-box icon-box-center text-center\">\n                <div class=\"icon-box-text p-last-0\">\n            \t\t\t\t<div class=\"testimonial-text line-height-small italic test_text first-reset last-reset is-italic\">\n            \n\n\t<div id=\"gap-506361897\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-506361897 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<p style=\"font-style: normal;\">&#8222;\u00cen c\u00e2teva zile de la administrarea NANO SOMA\u00ae, am observat c\u0103 m\u0103 sim\u021beam mai energic\u0103, pielea mea ar\u0103ta mai bine \u0219i ochii mei erau mai lumino\u0219i. \u00cencurajat\u0103, am continuat s\u0103 folosesc NANO SOMA \u0219i am constatat c\u0103 nivelul meu de energie era \u00een cre\u0219tere. Programul meu de fitness \u0219i exerci\u021bii \u00eencepea s\u0103 prezinte \u00eembun\u0103t\u0103\u021biri \u0219i sim\u021beam c\u0103 am puterea de a finaliza antrenamente mai mari. Mai important, pl\u0103m\u00e2nii mei se sim\u021beau minunat!\u201d  <\/p>\n\n          <\/div>\n          <div class=\"testimonial-meta pt-half\">\n             <strong class=\"testimonial-name test_name\">Mark<\/strong>\n                          <span class=\"testimonial-company test_company\"><\/span>\n          <\/div>\n        <\/div>\n  <\/div>\n\n  \n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\n<style>\n#row-1330444277 > .col > .col-inner {\n  padding: 25px 25px 25px 25px;\n  background-color: rgb(255,255,255);\n}\n<\/style>\n<\/div>\n<div class=\"row\"  id=\"row-1756129366\">\n\n\n\t<div id=\"col-360016861\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"#leaveyourreview\" class=\"button primary is-larger\" style=\"border-radius:10px;\">\n\t\t<span>Las\u0103-\u021bi recenzia<\/span>\n\t<\/a>\n\n\n\n\n\t<div id=\"leaveyourreview\"\n\t     class=\"lightbox-by-id lightbox-content mfp-hide lightbox-white \"\n\t     style=\"max-width:850px ;padding:30px\">\n\t\t\n\t<section class=\"section\" id=\"section_352879407\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-584924851\">\n\n\n\t<div id=\"col-688417977\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\n<style id=\"wpforms-css-vars-3042\">\n\t\t\t\t#wpforms-3042 {\n\t\t\t\t--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-3042\"><form id=\"wpforms-form-3042\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"3042\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/ro\/wp-json\/wp\/v2\/pages\/11202?wpforms_form_id=3042\" data-token=\"95d475596f7991c5506871502262a1a7\" data-token-time=\"1788351560\"><noscript class=\"wpforms-error-noscript\">V\u0103 rug\u0103m s\u0103 activa\u021bi JavaScript \u00een browserul dvs. pentru a completa acest formular.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">V\u0103 rug\u0103m s\u0103 activa\u021bi JavaScript \u00een browserul dvs. pentru a completa acest formular.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-3042-field_1-container\" class=\"wpforms-field wpforms-field-divider\" data-field-type=\"divider\" data-field-id=\"1\"><h3 id=\"wpforms-3042-field_1\" aria-errormessage=\"wpforms-3042-field_1-error\">Informa\u021bii personale<\/h3><\/div><div id=\"wpforms-3042-field_2-container\" class=\"wpforms-field wpforms-field-layout\" data-field-type=\"layout\" data-field-id=\"2\"><div class=\"wpforms-field-layout-columns wpforms-field-layout-preset-50-50\"><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-3042-field_3-container\" class=\"wpforms-field wpforms-field-name\" data-field-type=\"name\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-3042-field_3\">Nume \u0219i prenume <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-3042-field_3\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][3]\" placeholder=\"de exemplu, Jane Smith\" aria-errormessage=\"wpforms-3042-field_3-error\" required><\/div><div id=\"wpforms-3042-field_5-container\" class=\"wpforms-field wpforms-field-phone\" data-field-type=\"phone\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-3042-field_5\">Telefon<\/label><input type=\"tel\" id=\"wpforms-3042-field_5\" class=\"wpforms-field-medium wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][5]\" aria-label=\"Telefon\" aria-errormessage=\"wpforms-3042-field_5-error\" ><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\" ><div id=\"wpforms-3042-field_4-container\" class=\"wpforms-field wpforms-field-email\" data-field-type=\"email\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-3042-field_4\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-3042-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" placeholder=\"de exemplu, janesmith@example.com\" spellcheck=\"false\" aria-errormessage=\"wpforms-3042-field_4-error\" required><\/div><\/div><\/div><\/div><div id=\"wpforms-3042-field_7-container\" class=\"wpforms-field wpforms-field-divider\" data-field-type=\"divider\" data-field-id=\"7\"><h3 id=\"wpforms-3042-field_7\" aria-errormessage=\"wpforms-3042-field_7-error\">M\u0103rturii detaliate<\/h3><\/div><div id=\"wpforms-3042-field_9-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-type=\"textarea\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-3042-field_9\">Textul m\u0103rturiei <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-3042-field_9\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][9]\" placeholder=\"de exemplu, folosesc produsul XYZ de un an, iar acesta mi-a transformat afacerea. Recomand cu c\u0103ldur\u0103! \" aria-errormessage=\"wpforms-3042-field_9-error\" required><\/textarea><\/div><div id=\"wpforms-3042-field_10-container\" class=\"wpforms-field wpforms-field-date-time\" data-field-type=\"date-time\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-3042-field_10\">Data m\u0103rturiei <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-datepicker-wrap\"><input type=\"text\" id=\"wpforms-3042-field_10\" class=\"wpforms-field-date-time-date wpforms-datepicker wpforms-field-required wpforms-field-large\" data-date-format=\"m\/d\/Y\" data-disable-past-dates=\"0\" data-input=\"true\" name=\"wpforms[fields][10][date]\" placeholder=\"MM\/DD\/YY\" aria-errormessage=\"wpforms-3042-field_10-error\" required><a title=\"Clear Date\" data-clear role=\"button\" tabindex=\"0\" class=\"wpforms-datepicker-clear\" aria-label=\"Clear Date\" style=\"display:none;\"><\/a><\/div><\/div><div id=\"wpforms-3042-field_22-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-type=\"file-upload\" data-field-id=\"22\"><label class=\"wpforms-field-label\" for=\"wpforms-3042-field_22\">\u00cenc\u0103rcare fi\u0219ier<\/label><div\n\t\tclass=\"wpforms-uploader \"\n\t\tdata-field-id=\"22\"\n\t\tdata-form-id=\"3042\"\n\t\tdata-input-name=\"wpforms_3042_22\"\n\t\tdata-extensions=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,x-wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages,json,gz\"\n\t\tdata-max-size=\"104857600\"\n\t\tdata-max-file-number=\"1\"\n\t\tdata-post-max-size=\"104857600\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Fi\u0219iere,  \t\t\t\t<span>Alege\u021bi fi\u0219ierele pentru \u00eenc\u0103rcare<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-3042-field_22\"\n\t\tname=\"wpforms_3042_22\" \t\tvalue=\"\">\n<\/div><div id=\"wpforms-3042-field_11-container\" class=\"wpforms-field wpforms-field-divider\" data-field-type=\"divider\" data-field-id=\"11\"><h3 id=\"wpforms-3042-field_11\" aria-errormessage=\"wpforms-3042-field_11-error\">Consim\u021b\u0103m\u00e2ntul mass-media<\/h3><\/div><div id=\"wpforms-3042-field_14-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"14\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Fotografie <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-3042-field_14\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-3042-field_14_1\" name=\"wpforms[fields][14][]\" value=\"Acord permisiunea de a utiliza o fotografie al\u0103turi de m\u0103rturie.\" aria-errormessage=\"wpforms-3042-field_14_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3042-field_14_1\">Acord permisiunea de a utiliza o fotografie al\u0103turi de m\u0103rturie.<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-3042-field_15-container\" class=\"wpforms-field wpforms-field-divider\" data-field-type=\"divider\" data-field-id=\"15\"><h3 id=\"wpforms-3042-field_15\" aria-errormessage=\"wpforms-3042-field_15-error\">Permisiuni de utilizare<\/h3><\/div><div id=\"wpforms-3042-field_16-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"16\"><fieldset><legend class=\"wpforms-field-label\">Selecta\u021bi unde poate fi utilizat\u0103 recomandarea <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-3042-field_16\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-3042-field_16_1\" name=\"wpforms[fields][16][]\" value=\"Site web\" aria-errormessage=\"wpforms-3042-field_16_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3042-field_16_1\">Site web<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-3042-field_16_2\" name=\"wpforms[fields][16][]\" value=\"Social Media\" aria-errormessage=\"wpforms-3042-field_16_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3042-field_16_2\">Social Media<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-3042-field_16_3\" name=\"wpforms[fields][16][]\" value=\"Materiale tip\u0103rite\" aria-errormessage=\"wpforms-3042-field_16_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3042-field_16_3\">Materiale tip\u0103rite<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-3042-field_18-container\" class=\"wpforms-field wpforms-field-divider\" data-field-type=\"divider\" data-field-id=\"18\"><h3 id=\"wpforms-3042-field_18\" aria-errormessage=\"wpforms-3042-field_18-error\">Consim\u021b\u0103m\u00e2nt \u0219i acord<\/h3><\/div><div id=\"wpforms-3042-field_19-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-type=\"checkbox\" data-field-id=\"19\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Consim\u021b\u0103m\u00e2nt <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-3042-field_19\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-3042-field_19_1\" name=\"wpforms[fields][19][]\" value=\"Prin prezenta, acord MagicDichol\u00ae dreptul de a utiliza m\u0103rturia mea a\u0219a cum este descris mai sus.\" aria-errormessage=\"wpforms-3042-field_19_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3042-field_19_1\">Prin prezenta, acord MagicDichol\u00ae dreptul de a utiliza m\u0103rturia mea a\u0219a cum este descris mai sus.<\/label><\/li><\/ul><\/fieldset><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"3042\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/magicdichol.info\/ro\/wp-json\/wp\/v2\/pages\/11202\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-3042\" class=\"wpforms-submit\" data-alt-text=\"Trimiterea...\" data-submit-text=\"Trimite\" aria-live=\"assertive\" value=\"wpforms-submit\">Trimite<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/magicdichol.info\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_352879407 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\t<\/div>\n\t\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_10412654 {\n  padding-top: 80px;\n  padding-bottom: 80px;\n  background-color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"bwfblock_default_font":"","footnotes":""},"class_list":["post-11202","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/magicdichol.info\/ro\/wp-json\/wp\/v2\/pages\/11202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magicdichol.info\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/magicdichol.info\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/magicdichol.info\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/magicdichol.info\/ro\/wp-json\/wp\/v2\/comments?post=11202"}],"version-history":[{"count":1,"href":"https:\/\/magicdichol.info\/ro\/wp-json\/wp\/v2\/pages\/11202\/revisions"}],"predecessor-version":[{"id":11203,"href":"https:\/\/magicdichol.info\/ro\/wp-json\/wp\/v2\/pages\/11202\/revisions\/11203"}],"wp:attachment":[{"href":"https:\/\/magicdichol.info\/ro\/wp-json\/wp\/v2\/media?parent=11202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}