{"id":18819,"date":"2026-01-15T23:55:00","date_gmt":"2026-01-16T04:55:00","guid":{"rendered":"https:\/\/magicdichol.info\/?p=18819"},"modified":"2026-01-15T23:55:29","modified_gmt":"2026-01-16T04:55:29","slug":"le-coin-du-fondateur-edition-9-les-croyances-dirigent-notre-vie-avec-puissance","status":"publish","type":"post","link":"https:\/\/magicdichol.info\/fr\/le-coin-du-fondateur-edition-9-les-croyances-dirigent-notre-vie-avec-puissance\/","title":{"rendered":"Le Coin du Fondateur Edition 9 : Les croyances dirigent notre vie avec puissance"},"content":{"rendered":"\n<p>Les croyances jouent un r\u00f4le important dans notre vie, bien plus que la plupart d&rsquo;entre nous ne le r\u00e9alisent. D&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, c&rsquo;est principalement ce que nous croyons qui d\u00e9termine ce que nous disons et faisons. La question qui se pose \u00e0 chacun d&rsquo;entre nous est la suivante : qui ou quoi a d\u00e9termin\u00e9 ces croyances ? Si ce n&rsquo;est pas vous, qui l&rsquo;a fait ?   <\/p>\n<p>Pour ceux d&rsquo;entre nous qui suivent un chemin spirituel, nos croyances fondamentales sont d\u00e9termin\u00e9es par notre exp\u00e9rience du Soi. Pour les autres, ces croyances sont largement d\u00e9termin\u00e9es par notre milieu social, notre famille, notre \u00e9ducation et ce qui nous parvient par le biais des m\u00e9dias grand public et sociaux. <\/p>\n<p>Pour ceux d&rsquo;entre nous qui n&rsquo;ont pas cultiv\u00e9 un noyau spirituel, nous prenons nos croyances pour nous-m\u00eames, puisque nous ne savons rien de notre nature au-del\u00e0 d&rsquo;elles. Nombreux sont ceux qui, chaque jour, meurent pour leurs convictions. <\/p>\n<p>Ceux qui dirigent notre monde, actuellement &#8211; mais je pense que ce ne sera pas pour longtemps &#8211; ont fait pr\u00e9valoir l&rsquo;id\u00e9e que nous sommes simplement des \u00eatres temporels et que nous vivons et mourons en tant que tels, ce qui signifie que l&rsquo;\u00e2me n&rsquo;existe pas et que la conscience est un produit de l&rsquo;esprit, ce qui n&rsquo;est manifestement pas le cas. La m\u00e9canique quantique a d\u00e9montr\u00e9, il y a une centaine d&rsquo;ann\u00e9es, que cela ne pouvait pas \u00eatre vrai et que l&rsquo;observateur jouait un r\u00f4le essentiel dans ce qui se manifestait. La c\u00e9l\u00e8bre <a href=\"https:\/\/en.wikipedia.org\/wiki\/Double-slit_experiment\" target=\"_blank\" rel=\"noopener\">exp\u00e9rience de la double fente de<\/a> 1801 montre que la lumi\u00e8re se comporte soit comme une onde, soit comme une particule, selon qu&rsquo;elle est observ\u00e9e ou non. Aujourd&rsquo;hui, il a \u00e9t\u00e9 d\u00e9montr\u00e9 que ce comportement s&rsquo;applique \u00e9galement aux \u00e9lectrons et m\u00eame aux atomes. Cela d\u00e9truit l&rsquo;id\u00e9e que nous ne sommes que des \u00eatres physiques. En outre, le r\u00e9cent ouvrage du Dr Dean Radin, <a href=\"https:\/\/share.google\/V8GCDDfRJ1rF40Grk\" target=\"_blank\" rel=\"noopener\">The Science of Magic : How the Mind Weaves the Fabric of Reality (La science de la magie : comment l&rsquo;esprit tisse la trame de la r\u00e9alit\u00e9<\/a>), pr\u00e9sente les preuves scientifiques de notre capacit\u00e9 \u00e0 influencer de mani\u00e8re d\u00e9montrable l&rsquo;issue d&rsquo;\u00e9v\u00e9nements al\u00e9atoires, ainsi que des exemples de ces processus \u00e0 l&rsquo;\u0153uvre dans la vie de tous les jours.     <\/p>\n<p>Je consid\u00e8re que mes croyances sont comme les v\u00eatements que je porte &#8211; je m&rsquo;en d\u00e9barrasse lorsqu&rsquo;une nouvelle ou meilleure compr\u00e9hension \u00e9merge. On dit que Steve Jobs d\u00e9fendait avec v\u00e9h\u00e9mence ce qu&rsquo;il consid\u00e9rait comme la meilleure solution &#8211; une forme de croyance. Cependant, si quelqu&rsquo;un le persuadait de l&rsquo;existence d&rsquo;une meilleure option, il se retournait d&rsquo;un coup et rejetait ce qu&rsquo;il venait de d\u00e9fendre avec passion. Steve \u00e9tait un homme profond\u00e9ment spirituel et ne tenait pas \u00e0 \u00ab\u00a0avoir raison\u00bb. Ceux qui l&rsquo;ont c\u00f4toy\u00e9 disaient qu&rsquo;il pouvait \u00ab\u00a0d\u00e9former la r\u00e9alit\u00e9\u00bb.    <\/p>\n<h2 style=\"text-align: center;\"><strong>Quel est le rapport avec NANO SOMA\u00ae ?  <\/strong><\/h2>\n<p>Les croyances ont un impact sur notre vie \u00e0 de nombreux niveaux. Si nous croyons que quelque chose est vrai, nous agissons avec confiance et cela a un impact sur notre corps physique ainsi que sur nos pens\u00e9es et nos sentiments. Dans certains cas, lorsqu&rsquo;il s&rsquo;agit de substances manifestement conscientes comme NANO SOMA, cela peut avoir un impact sur leur efficacit\u00e9 dans notre corps. Raghu en a parl\u00e9 d\u00e8s le d\u00e9but en ce qui concerne les r\u00e9sultats obtenus avec NANO SOMA.   <\/p>\n<p>Ainsi, si vous avez pris le temps de comprendre comment et pourquoi NANO SOMA agit dans votre corps, et si vous avez \u00e9tudi\u00e9 les t\u00e9moignages d&rsquo;autres personnes, vous avez beaucoup plus de chances d&rsquo;obtenir des r\u00e9sultats positifs gr\u00e2ce \u00e0 cette particule &#8211; une particule qui a apport\u00e9 le sch\u00e9ma directeur de la vie humaine, et peut-\u00eatre de toute vie, sur la plan\u00e8te.<\/p>\n<p>Dr. Richard Presser<\/p>\n\n\t<section class=\"section\" id=\"section_840397137\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1733345454\">\n\n\n\t<div id=\"col-1971897516\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3500429069\" class=\"text\">\n\t\t\n\n<p>\u00cates-vous pr\u00eat \u00e0 voir ce qu&rsquo;il peut faire pour vous ?<\/p>\n<p style=\"font-size:80%\">Appuyez sur le bouton ci-dessous et d\u00e9couvrez comment vous pouvez le faire !<\/p>\n\t\t\n<style>\n#text-3500429069 {\n  font-size: 1.55rem;\n  line-height: 1.4;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-3500429069 {\n    font-size: 1.65rem;\n    line-height: 0.75;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/magicdichol.info\/fr\/acheter\/\" target=\"_blank\" class=\"button primary is-large\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>J&#039;AI ENVIE DE L&#039;ESSAYER !<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-720315998\">\n\n\n\t<div id=\"col-1692100244\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:#767676;border-width:2px 2px 2px 2px;\">\n\t<\/div>\n\t\t\t\n\n\t<div id=\"text-223461799\" class=\"text\">\n\t\t\n\n<p><strong>*Ces d\u00e9clarations n&rsquo;ont pas \u00e9t\u00e9 \u00e9valu\u00e9es par la Food and Drug Administration des \u00c9tats-Unis. Ce produit n&rsquo;est pas destin\u00e9 \u00e0 diagnostiquer ou \u00e0 prescrire une quelconque condition m\u00e9dicale, ni \u00e0 pr\u00e9venir, traiter, att\u00e9nuer ou gu\u00e9rir une telle condition. Si vous souffrez d&rsquo;une maladie ou d&rsquo;un probl\u00e8me m\u00e9dical, consultez votre fournisseur de soins de sant\u00e9.  <\/strong><\/p>\n\t\t\n<style>\n#text-223461799 {\n  font-size: 0.9rem;\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1692100244 > .col-inner {\n  padding: 10px 20px 5px 20px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_840397137 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_840397137 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"<p>Les croyances fa\u00e7onnent notre vie et influencent l&rsquo;efficacit\u00e9 de NANO SOMA\u00ae. Richard Presser explique comment les influences spirituelles et sociales d\u00e9terminent notre perspective unique. La science, y compris la m\u00e9canique quantique, sugg\u00e8re que nous sommes plus que des \u00eatres physiques. Comprendre le m\u00e9canisme de NANO SOMA\u00ae et lire les t\u00e9moignages favorise la confiance, ce qui a un impact sur le corps et permet d&rsquo;obtenir des r\u00e9sultats positifs.   <\/p>\n","protected":false},"author":4,"featured_media":18821,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"bwfblock_default_font":"","footnotes":""},"categories":[1909],"tags":[2955,2956,96,2957],"class_list":["post-18819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-le-coin-du-fondateur","tag-beliefs","tag-consciousness","tag-nanosoma","tag-quantum-mechanics"],"_links":{"self":[{"href":"https:\/\/magicdichol.info\/fr\/wp-json\/wp\/v2\/posts\/18819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magicdichol.info\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/magicdichol.info\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/magicdichol.info\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/magicdichol.info\/fr\/wp-json\/wp\/v2\/comments?post=18819"}],"version-history":[{"count":1,"href":"https:\/\/magicdichol.info\/fr\/wp-json\/wp\/v2\/posts\/18819\/revisions"}],"predecessor-version":[{"id":18823,"href":"https:\/\/magicdichol.info\/fr\/wp-json\/wp\/v2\/posts\/18819\/revisions\/18823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magicdichol.info\/fr\/wp-json\/wp\/v2\/media\/18821"}],"wp:attachment":[{"href":"https:\/\/magicdichol.info\/fr\/wp-json\/wp\/v2\/media?parent=18819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/magicdichol.info\/fr\/wp-json\/wp\/v2\/categories?post=18819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/magicdichol.info\/fr\/wp-json\/wp\/v2\/tags?post=18819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}