{"id":20462,"date":"2026-05-10T11:38:00","date_gmt":"2026-05-10T16:38:00","guid":{"rendered":"https:\/\/magicdichol.info\/wer-haette-das-gedacht-frage-und-antwort-mit-john-kosten-wert-und-nutzen\/"},"modified":"2026-05-13T08:58:58","modified_gmt":"2026-05-13T13:58:58","slug":"wer-haette-das-gedacht-frage-und-antwort-mit-john-kosten-wert-und-nutzen","status":"publish","type":"post","link":"https:\/\/magicdichol.info\/de\/wer-haette-das-gedacht-frage-und-antwort-mit-john-kosten-wert-und-nutzen\/","title":{"rendered":"Wer h\u00e4tte das gedacht? Frage und Antwort mit John: Kosten, Wert und Nutzen"},"content":{"rendered":"\n<h2 style=\"text-align: center;\"><strong>Wie w\u00fcrden Sie den wahren Wert von NANO SOMA\u00ae erkl\u00e4ren?<\/strong><\/h2>\n<p>In &#8222;Lives of the Eminent Philosophers\u201c finden wir dieses Zitat von Diogenes von Sinope:<\/p>\n<p><em>Wir verkaufen Dinge von gro\u00dfem Wert f\u00fcr Dinge von sehr geringem Wert, und umgekehrt.<\/em><\/p>\n<p>Offenbar k\u00f6nnen Sie bei Plume Blanche ein mit Diamanten besetztes Sofa f\u00fcr 200.000 Dollar kaufen. Wahrscheinlich ist es auch m\u00f6glich, eine Person zu beauftragen, eine andere f\u00fcr $500 zu t\u00f6ten. Wenn Sie also jemanden behaupten h\u00f6ren, der Markt entscheide, was die Dinge wert sind, dann sollten Sie sich dar\u00fcber im Klaren sein, dass der Markt zwar rational sein mag, aber die Menschen, aus denen er besteht, es oft nicht sind.  <\/p>\n<p>Diogenes betonte den wahren Wert der Dinge. In der heutigen unlogischen Welt, in der wir sehen, wie die Menschen um uns herum ein Verm\u00f6gen f\u00fcr Schmuck ausgeben (den sie nicht mitnehmen k\u00f6nnen, wenn sie sterben!), ist es leicht, den wahren Wert aus den Augen zu verlieren. <\/p>\n<p>Wir denken vielleicht, dass diejenigen, die Geld haben, immer gute Entscheidungen treffen, also k\u00f6nnte ihr Beispiel auch f\u00fcr uns eine gute Investition sein.<\/p>\n<p>Aber das ist es nat\u00fcrlich nicht. Die guten Dinge im Leben kosten, was sie kosten. Die unn\u00f6tigen Dinge sind es nicht wert, um jeden Preis.  <\/p>\n<p>Manche sagen, dass es nur zwei Dinge gibt, die es wert sind, erworben zu werden: geistiges und k\u00f6rperliches Wohlbefinden.<\/p>\n<p>F\u00fcr Erstere gibt es eine Vielzahl von M\u00f6glichkeiten, sich mit Ihrem h\u00f6heren Selbst zu verbinden. F\u00fcr Letztere ist die Suche nach einer einfachen und nat\u00fcrlichen L\u00f6sung zur Wiederherstellung und Erhaltung eines gesunden, starken K\u00f6rpers ein Ergebnis, nach dem viele suchen. Heute mehr denn je.  <\/p>\n<p>Dann sind Sie bei uns genau richtig. NANO SOMA ist das einzige uns bekannte Produkt, das Ihren K\u00f6rper dazu veranlasst, seine eigenen angeborenen und bemerkenswerten Heilungsf\u00e4higkeiten in Gang zu setzen oder zu verst\u00e4rken.* <\/p>\n<p>NANO SOMA geh\u00f6rt zu den bereits erw\u00e4hnten (wirklich) guten Dingen im Leben.<\/p>\n<p>NANO SOMA kostet zwar, was es kostet, aber sein Nutzen ist von unermesslichem Wert.<\/p>\n\n\t<section class=\"section\" id=\"section_1413538978\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-757717429\">\n\n\n\t<div id=\"col-2016548910\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2587402811\" class=\"text\">\n\t\t\n\n<p>Sind Sie bereit zu sehen, was es f\u00fcr Sie tun kann?<\/p>\n<p style=\"font-size:80%\">Tippen Sie auf die Schaltfl\u00e4che unten und entdecken Sie, wie Sie das tun k\u00f6nnen!<\/p>\n\t\t\n<style>\n#text-2587402811 {\n  font-size: 1.55rem;\n  line-height: 1.4;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-2587402811 {\n    font-size: 1.65rem;\n    line-height: 0.75;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"#revcent-popup\" target=\"_blank\" class=\"button primary is-large\" rel=\"noopener\" style=\"border-radius:10px;\">\n\t\t<span>ICH M\u00d6CHTE DAS AUSPROBIEREN!<\/span>\n\t<\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1353553112\">\n\n\n\t<div id=\"col-43436945\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:#767676;border-width:2px 2px 2px 2px;\">\n\t<\/div>\n\t\t\t\n\n\t<div id=\"text-3854445736\" class=\"text\">\n\t\t\n\n<p><strong>*Diese Aussagen wurden nicht von der US Food and Drug Administration bewertet. Dieses Produkt ist nicht dazu bestimmt, Krankheiten zu diagnostizieren oder zu verschreiben oder solche Krankheiten zu verhindern, zu behandeln, zu lindern oder zu heilen. Wenn Sie eine Krankheit oder ein medizinisches Problem haben, wenden Sie sich an Ihren Arzt.  <\/strong><\/p>\n\t\t\n<style>\n#text-3854445736 {\n  font-size: 0.9rem;\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-43436945 > .col-inner {\n  padding: 10px 20px 5px 20px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1413538978 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_1413538978 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"<p>In &#8222;Lives of the Eminent Philosophers\u201c finden wir dieses Zitat von Diogenes von Sinope:<\/p>\n<p>Wir verkaufen Dinge von gro\u00dfem Wert f\u00fcr Dinge von sehr geringem Wert, und umgekehrt.<\/p>\n","protected":false},"author":4,"featured_media":20465,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"bwfblock_default_font":"","footnotes":""},"categories":[1755],"tags":[3570,3572,3571,1303,1707],"class_list":["post-20462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forschung-zentral","tag-gesundheit-wert","tag-investition-in-die-gesundheit","tag-korperliches-wohlbefinden","tag-nano-soma-de","tag-naturheilkunde"],"_links":{"self":[{"href":"https:\/\/magicdichol.info\/de\/wp-json\/wp\/v2\/posts\/20462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/magicdichol.info\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/magicdichol.info\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/magicdichol.info\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/magicdichol.info\/de\/wp-json\/wp\/v2\/comments?post=20462"}],"version-history":[{"count":1,"href":"https:\/\/magicdichol.info\/de\/wp-json\/wp\/v2\/posts\/20462\/revisions"}],"predecessor-version":[{"id":20466,"href":"https:\/\/magicdichol.info\/de\/wp-json\/wp\/v2\/posts\/20462\/revisions\/20466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/magicdichol.info\/de\/wp-json\/wp\/v2\/media\/20465"}],"wp:attachment":[{"href":"https:\/\/magicdichol.info\/de\/wp-json\/wp\/v2\/media?parent=20462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/magicdichol.info\/de\/wp-json\/wp\/v2\/categories?post=20462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/magicdichol.info\/de\/wp-json\/wp\/v2\/tags?post=20462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}